{"id":4524,"date":"2022-06-28T14:29:41","date_gmt":"2022-06-28T12:59:41","guid":{"rendered":"https:\/\/www.personalizeon.com\/non%20class\u00e9\/aimants-de-mariage-en-metal-rectangulaires-personnalises\/"},"modified":"2022-11-17T19:23:37","modified_gmt":"2022-11-17T17:53:37","slug":"aimants-mariage-rectangulaire-plaque-personnalisee","status":"publish","type":"product","link":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/","title":{"rendered":"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s"},"content":{"rendered":"<p>Aimants rectangulaires personnalis\u00e9s 78X53 mm pour les mariages.  <strong>Aimant pour r\u00e9frig\u00e9rateur avec badge personnalisable.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aimants rectangulaires personnalis\u00e9s avec plaque m\u00e9tallique<\/p>\n<ul>\n<li>Aimant m\u00e9tallique rectangulaire 78&#215;53 mm<\/li>\n<li>Personnalis\u00e9 avec le design de votre choix<\/li>\n<li>Faces imprimables : 1<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":4338,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[211,167,196,203],"product_tag":[],"class_list":["post-4524","product","type-product","status-publish","has-post-thumbnail","product_cat-aimants-a-plaques","product_cat-aimants-personnalises","product_cat-aimants-pour-les-mariages","product_cat-cadeaux-pour-les-mariages","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com\" \/>\n<meta property=\"og:description\" content=\"Aimants rectangulaires personnalis\u00e9s avec plaque m\u00e9tallique  Aimant m\u00e9tallique rectangulaire 78x53 mm  Personnalis\u00e9 avec le design de votre choix  Faces imprimables : 1 &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/\" \/>\n<meta property=\"og:site_name\" content=\"www.personalizeon.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-17T17:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.personalizeon.com\/wp-content\/uploads\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/\",\"url\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/\",\"name\":\"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.personalizeon.com\\\/wp-content\\\/uploads\\\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg\",\"datePublished\":\"2022-06-28T12:59:41+00:00\",\"dateModified\":\"2022-11-17T17:53:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.personalizeon.com\\\/wp-content\\\/uploads\\\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.personalizeon.com\\\/wp-content\\\/uploads\\\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/aimants-personnalises\\\/aimants-mariage-rectangulaire-plaque-personnalisee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/\",\"name\":\"www.personalizeon.com\",\"description\":\"Art&iacute;culos personalizados para tu empresa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#organization\",\"name\":\"www.personalizeon.com\",\"url\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.personalizeon.com\\\/wp-content\\\/uploads\\\/cropped-on-logo-personalizeon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.personalizeon.com\\\/wp-content\\\/uploads\\\/cropped-on-logo-personalizeon.jpg\",\"width\":200,\"height\":119,\"caption\":\"www.personalizeon.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.personalizeon.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/","og_locale":"fr_FR","og_type":"article","og_title":"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com","og_description":"Aimants rectangulaires personnalis\u00e9s avec plaque m\u00e9tallique  Aimant m\u00e9tallique rectangulaire 78x53 mm  Personnalis\u00e9 avec le design de votre choix  Faces imprimables : 1 &nbsp;","og_url":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/","og_site_name":"www.personalizeon.com","article_modified_time":"2022-11-17T17:53:37+00:00","og_image":[{"url":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/","url":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/","name":"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s - www.personalizeon.com","isPartOf":{"@id":"https:\/\/www.personalizeon.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/#primaryimage"},"image":{"@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg","datePublished":"2022-06-28T12:59:41+00:00","dateModified":"2022-11-17T17:53:37+00:00","breadcrumb":{"@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/#primaryimage","url":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg","contentUrl":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/IMANES-BODA-HORIZONTAL-78x53-mm-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.personalizeon.com\/fr\/aimants-personnalises\/aimants-mariage-rectangulaire-plaque-personnalisee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.personalizeon.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.personalizeon.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Aimants de mariage en m\u00e9tal rectangulaires personnalis\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.personalizeon.com\/fr\/#website","url":"https:\/\/www.personalizeon.com\/fr\/","name":"www.personalizeon.com","description":"Art&iacute;culos personalizados para tu empresa","publisher":{"@id":"https:\/\/www.personalizeon.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.personalizeon.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.personalizeon.com\/fr\/#organization","name":"www.personalizeon.com","url":"https:\/\/www.personalizeon.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.personalizeon.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/cropped-on-logo-personalizeon.jpg","contentUrl":"https:\/\/www.personalizeon.com\/wp-content\/uploads\/cropped-on-logo-personalizeon.jpg","width":200,"height":119,"caption":"www.personalizeon.com"},"image":{"@id":"https:\/\/www.personalizeon.com\/fr\/#\/schema\/logo\/image\/"}}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"50":1.13,"100":1.12,"150":1.1,"500":1,"1000":0.72},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product\/4524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/comments?post=4524"}],"version-history":[{"count":0,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product\/4524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/media\/4338"}],"wp:attachment":[{"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/media?parent=4524"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product_brand?post=4524"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product_cat?post=4524"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.personalizeon.com\/fr\/wp-json\/wp\/v2\/product_tag?post=4524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}